{"id":131075,"date":"2019-09-01T09:30:46","date_gmt":"2019-09-01T09:30:46","guid":{"rendered":"https:\/\/travelqa.com\/alta-comision-de-uganda-en-dar-es-salaam-tanzania\/"},"modified":"2019-09-01T09:30:46","modified_gmt":"2019-09-01T09:30:46","slug":"alta-comision-de-uganda-en-dar-es-salaam-tanzania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/alta-comision-de-uganda-en-dar-es-salaam-tanzania\/","title":{"rendered":"Alta Comisi\u00f3n de Uganda en Dar-es-Salaam, Tanzania"},"content":{"rendered":"<div id=\"trave-3455783741\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Alta Comisi\u00f3n de Uganda en Dar-es-Salaam, Tanzania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nOysterbay, 25 Msasani Road<br \/>\nP. O. Box 6237<br \/>\nDar-es-Salaam<br \/>\nTanzania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Nora Lema Katabarwa, Alta Comisionada<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+255) 222-667 391<br \/>\n<strong>Fax:<\/strong> (+255) 222-667 224<br \/>\n<strong>Email:<\/strong> daressalaam@mofa.go.ug<br \/>\ninfo@ughc.co.tz<br \/>\n<strong>Sitio web:<\/strong> www.daressalaam.mofa.go.ug<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1587052807\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Alta Comisi\u00f3n de Uganda en Dar-es-Salaam, Tanzania Direcci\u00f3n: Oysterbay, 25 Msasani Road P. O. Box 6237 Dar-es-Salaam Tanzania Embajador: Nora Lema Katabarwa, Alta Comisionada Tel\u00e9fono: (+255) 222-667 391 Fax: (+255) 222-667 224 Email: daressalaam@mofa.go.ug info@ughc.co.tz Sitio web: www.daressalaam.mofa.go.ug Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13724,15103,6661,6770],"tags":[13640],"class_list":["post-131075","post","type-post","status-publish","format-standard","hentry","category-altas-comisiones-de-uganda","category-altas-comisiones-en-tanzania","category-tanzania","category-uganda","tag-alta-comision"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/131075"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=131075"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/131075\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=131075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=131075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=131075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}