{"id":130753,"date":"2019-09-01T09:27:20","date_gmt":"2019-09-01T09:27:20","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-cabo-verde-en-ginebra-suiza\/"},"modified":"2019-09-01T09:27:20","modified_gmt":"2019-09-01T09:27:20","slug":"consulado-general-de-cabo-verde-en-ginebra-suiza","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-cabo-verde-en-ginebra-suiza\/","title":{"rendered":"Consulado General de Cabo Verde en Ginebra, Suiza"},"content":{"rendered":"<div id=\"trave-454167024\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Cabo Verde en Ginebra, Suiza<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1202 Ginebra<br \/>\nSuiza<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Alcides Barros, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+41) 22 731 35 40<br \/>\n<strong>Fax:<\/strong> (+41) 22 731 35 40<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2077109282\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Cabo Verde en Ginebra, Suiza Direcci\u00f3n: 1202 Ginebra Suiza Embajador: Mr Alcides Barros, C\u00f3nsul General Tel\u00e9fono: (+41) 22 731 35 40 Fax: (+41) 22 731 35 40 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13499,14017,15057,13065],"tags":[12988],"class_list":["post-130753","post","type-post","status-publish","format-standard","hentry","category-cabo-verde","category-consulado-general-de-cabo-verde","category-consulado-general-en-suiza","category-suiza","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130753"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=130753"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130753\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=130753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=130753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=130753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}