{"id":130618,"date":"2019-09-01T09:25:58","date_gmt":"2019-09-01T09:25:58","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-nueva-zelanda-en-ginebra-suiza\/"},"modified":"2019-09-01T09:25:58","modified_gmt":"2019-09-01T09:25:58","slug":"consulado-general-de-nueva-zelanda-en-ginebra-suiza","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-nueva-zelanda-en-ginebra-suiza\/","title":{"rendered":"Consulado General de Nueva Zelanda en Ginebra, Suiza"},"content":{"rendered":"<div id=\"trave-1587301215\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Nueva Zelanda en Ginebra, Suiza<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n1218 Le Grand-Saconnex<br \/>\n1200 Ginebra<br \/>\nSuiza<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+41) (0) 22 929 03 74<br \/>\n<strong>Fax:<\/strong> (+41) (0) 22 929 03 74<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-584166749\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Nueva Zelanda en Ginebra, Suiza Direcci\u00f3n: 1218 Le Grand-Saconnex 1200 Ginebra Suiza Embajador: Tel\u00e9fono: (+41) (0) 22 929 03 74 Fax: (+41) (0) 22 929 03 74 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13667,15057,13567,13065],"tags":[12988],"class_list":["post-130618","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-nueva-zelanda","category-consulado-general-en-suiza","category-nueva-zelanda","category-suiza","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130618"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=130618"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130618\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=130618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=130618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=130618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}