{"id":130561,"date":"2019-09-01T09:25:19","date_gmt":"2019-09-01T09:25:19","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-costa-rica-en-berna-suiza\/"},"modified":"2019-09-01T09:25:19","modified_gmt":"2019-09-01T09:25:19","slug":"embajada-de-costa-rica-en-berna-suiza","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-costa-rica-en-berna-suiza\/","title":{"rendered":"Embajada de Costa Rica en Berna, Suiza"},"content":{"rendered":"<div id=\"trave-1556525511\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Costa Rica en Berna, Suiza<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n3011 Berna<br \/>\nSuiza<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+41) 31 37 27 887<br \/>\n<strong>Fax:<\/strong> (+41) 31 37 27 834<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 15.00 con cita previa<\/p>\n<div id=\"trave-1109745594\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Costa Rica en Berna, Suiza Direcci\u00f3n: 3011 Berna Suiza Embajador: Tel\u00e9fono: (+41) 31 37 27 887 Fax: (+41) 31 37 27 834 Email: Sitio web: Horas de oficina: 09.00 a 15.00 con cita previa<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5199,13547,15058,13065],"tags":[12975],"class_list":["post-130561","post","type-post","status-publish","format-standard","hentry","category-costa-rica","category-embajadas-costarricenses","category-embajadas-en-suiza","category-suiza","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130561"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=130561"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130561\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=130561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=130561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=130561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}