{"id":130031,"date":"2019-09-01T09:19:37","date_gmt":"2019-09-01T09:19:37","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-lituania-en-colombo-sri-lanka\/"},"modified":"2019-09-01T09:19:37","modified_gmt":"2019-09-01T09:19:37","slug":"consulado-de-lituania-en-colombo-sri-lanka","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-lituania-en-colombo-sri-lanka\/","title":{"rendered":"Consulado de Lituania en Colombo, Sri Lanka"},"content":{"rendered":"<div id=\"trave-1851143368\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Lituania en Colombo, Sri Lanka<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPlanta 33 West Tower<br \/>\nWorld Trade Center<br \/>\nColombo 01<br \/>\nSri Lanka<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Ramasamy Muthusamy Manivannan, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+94) 11 243 4000<br \/>\n<strong>Fax:<\/strong> (+94) 11 243 4049<br \/>\n<strong>Email:<\/strong> consulate@supreme.lk<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2113621329\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Lituania en Colombo, Sri Lanka Direcci\u00f3n: Planta 33 West Tower World Trade Center Colombo 01 Sri Lanka Embajador: Ramasamy Muthusamy Manivannan, C\u00f3nsul Honorario Tel\u00e9fono: (+94) 11 243 4000 Fax: (+94) 11 243 4049 Email: consulate@supreme.lk Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13608,15039,13184,6578],"tags":[12978],"class_list":["post-130031","post","type-post","status-publish","format-standard","hentry","category-consulados-de-lituania","category-consulados-en-sri-lanka","category-lituania","category-sri-lanka","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130031"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=130031"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/130031\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=130031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=130031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=130031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}