{"id":129950,"date":"2019-09-01T09:18:28","date_gmt":"2019-09-01T09:18:28","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-venezuela-en-barcelona-%e2%80%8b%e2%80%8bespana\/"},"modified":"2019-09-01T09:18:28","modified_gmt":"2019-09-01T09:18:28","slug":"consulado-general-de-venezuela-en-barcelona-%e2%80%8b%e2%80%8bespana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-venezuela-en-barcelona-%e2%80%8b%e2%80%8bespana\/","title":{"rendered":"Consulado General de Venezuela en Barcelona, \u200b\u200bEspa\u00f1a"},"content":{"rendered":"<div id=\"trave-1664444932\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado venezolano en Barcelona, \u200b\u200bEspa\u00f1a<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPlaza Urquinaona, n\u00ba 6, piso 6, punto A<br \/>\n08010 Barcelona<br \/>\nEspa\u00f1a<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Ricardo Cahella Mateo, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+34) 93 324 71 55<br \/>\n<strong>Fax:<\/strong> (+34) 93 301 47 38<br \/>\n<strong>Email:<\/strong> contacto@consulvenbarcelona.com<br \/>\n<strong>Sitio web:<\/strong> barcelona.consulado.gob.ve<\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 12.00<\/p>\n<div id=\"trave-2074498087\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado venezolano en Barcelona, \u200b\u200bEspa\u00f1a Direcci\u00f3n: Plaza Urquinaona, n\u00ba 6, piso 6, punto A 08010 Barcelona Espa\u00f1a Embajador: Ricardo Cahella Mateo, C\u00f3nsul General Tel\u00e9fono: (+34) 93 324 71 55 Fax: (+34) 93 301 47 38 Email: contacto@consulvenbarcelona.com Sitio web: barcelona.consulado.gob.ve Horas de oficina: 09.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15028,13627,13134,6866],"tags":[12988],"class_list":["post-129950","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-espana","category-consulado-general-venezolano","category-espana","category-venezuela","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129950"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129950"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129950\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}