{"id":129878,"date":"2019-09-01T09:17:42","date_gmt":"2019-09-01T09:17:42","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-malasia-en-barcelona-%e2%80%8b%e2%80%8bespana\/"},"modified":"2019-09-01T09:17:42","modified_gmt":"2019-09-01T09:17:42","slug":"consulado-general-de-malasia-en-barcelona-%e2%80%8b%e2%80%8bespana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-malasia-en-barcelona-%e2%80%8b%e2%80%8bespana\/","title":{"rendered":"Consulado General de Malasia en Barcelona, \u200b\u200bEspa\u00f1a"},"content":{"rendered":"<div id=\"trave-2854823699\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Malasia en Barcelona, \u200b\u200bEspa\u00f1a<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCalle Munner 10<br \/>\n08022 Barcelona<br \/>\nEspa\u00f1a<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Jorge Martinez Rotllan, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+34) 93 512 37 94<br \/>\n(+34) 93 417 09 11<br \/>\n<strong>Fax:<\/strong> (+34) 93 417 25 37<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.30 a 14.00<\/p>\n<div id=\"trave-2213460765\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Malasia en Barcelona, \u200b\u200bEspa\u00f1a Direcci\u00f3n: Calle Munner 10 08022 Barcelona Espa\u00f1a Embajador: Mr Jorge Martinez Rotllan, C\u00f3nsul General Honorario Tel\u00e9fono: (+34) 93 512 37 94 (+34) 93 417 09 11 Fax: (+34) 93 417 25 37 Email: Sitio web: Horas de oficina: 09.30 a 14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13711,15028,13134,13290],"tags":[12988],"class_list":["post-129878","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-malasia","category-consulado-general-en-espana","category-espana","category-malasia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129878"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129878"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129878\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}