{"id":129787,"date":"2019-09-01T09:16:58","date_gmt":"2019-09-01T09:16:58","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-arabia-saudita-en-malaga-espana\/"},"modified":"2019-09-01T09:16:58","modified_gmt":"2019-09-01T09:16:58","slug":"consulado-general-de-arabia-saudita-en-malaga-espana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-arabia-saudita-en-malaga-espana\/","title":{"rendered":"Consulado General de Arabia Saudita en M\u00e1laga, Espa\u00f1a"},"content":{"rendered":"<div id=\"trave-254635230\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Arabia Saudita en M\u00e1laga, Espa\u00f1a<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nC \/ Mauricio Moro 2<br \/>\nEdificio Eurocom, bloque sur segunda planta<br \/>\n29006 M\u00e1laga<br \/>\nEspa\u00f1a<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Abdulhadi MA Al Shafi, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+34) 95 232 44 97<br \/>\n(+34) 95 231 03 58<br \/>\n<strong>Fax:<\/strong> (+34) 95 239 76 16<br \/>\n<strong>Email:<\/strong> escon@mofa.gov.sa<br \/>\nconsulado@saudimalaga.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 15.00<\/p>\n<div id=\"trave-273963091\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Arabia Saudita en M\u00e1laga, Espa\u00f1a Direcci\u00f3n: C \/ Mauricio Moro 2 Edificio Eurocom, bloque sur segunda planta 29006 M\u00e1laga Espa\u00f1a Embajador: Sr. Abdulhadi MA Al Shafi, C\u00f3nsul General Tel\u00e9fono: (+34) 95 232 44 97 (+34) 95 231 03 58 Fax: (+34) 95 239 76 16 Email: escon@mofa.gov.sa consulado@saudimalaga.com Sitio web: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13157,13715,15028,13134],"tags":[12988],"class_list":["post-129787","post","type-post","status-publish","format-standard","hentry","category-arabia-saudita","category-consulado-general-de-arabia-saudita","category-consulado-general-en-espana","category-espana","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129787"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129787"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129787\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}