{"id":129725,"date":"2019-09-01T09:16:24","date_gmt":"2019-09-01T09:16:24","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-dinamarca-en-barcelona-%e2%80%8b%e2%80%8bespana\/"},"modified":"2019-09-01T09:16:24","modified_gmt":"2019-09-01T09:16:24","slug":"consulado-general-de-dinamarca-en-barcelona-%e2%80%8b%e2%80%8bespana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-dinamarca-en-barcelona-%e2%80%8b%e2%80%8bespana\/","title":{"rendered":"Consulado General de Dinamarca en Barcelona, \u200b\u200bEspa\u00f1a"},"content":{"rendered":"<div id=\"trave-1261329997\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado dan\u00e9s en Barcelona, \u200b\u200bEspa\u00f1a<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRambla de Catalu\u00f1a, 45, 4 &#8211; 2<br \/>\n08007 Barcelona<br \/>\nEspa\u00f1a<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Lau K. Andersen, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+34) 93 488 0222<br \/>\n<strong>Fax:<\/strong> (+34) 93 487 6736<br \/>\n<strong>Email:<\/strong> info@dk-konsulat.es<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00-13.00<\/p>\n<div id=\"trave-1034755070\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado dan\u00e9s en Barcelona, \u200b\u200bEspa\u00f1a Direcci\u00f3n: Rambla de Catalu\u00f1a, 45, 4 &#8211; 2 08007 Barcelona Espa\u00f1a Embajador: Mr Lau K. Andersen, C\u00f3nsul General Honorario Tel\u00e9fono: (+34) 93 488 0222 Fax: (+34) 93 487 6736 Email: info@dk-konsulat.es Sitio web: Horas de oficina: 10.00-13.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13712,15028,13136,13134],"tags":[12988],"class_list":["post-129725","post","type-post","status-publish","format-standard","hentry","category-consulado-general-danes","category-consulado-general-en-espana","category-dinamarca","category-espana","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129725"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129725"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129725\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}