{"id":129637,"date":"2019-09-01T09:15:33","date_gmt":"2019-09-01T09:15:33","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-ecuador-en-valencia-espana\/"},"modified":"2019-09-01T09:15:33","modified_gmt":"2019-09-01T09:15:33","slug":"consulado-general-de-ecuador-en-valencia-espana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-ecuador-en-valencia-espana\/","title":{"rendered":"Consulado General de Ecuador en Valencia, Espa\u00f1a"},"content":{"rendered":"<div id=\"trave-3816880692\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado ecuatoriano en Valencia, Espa\u00f1a<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n46002 Valencia<br \/>\nEspa\u00f1a<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+34) 96 342 7509<br \/>\n<strong>Fax:<\/strong> (+34) 96 351 9840<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> valencia.consulado.gob.ec<\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30-15.00<\/p>\n<div id=\"trave-1317462054\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado ecuatoriano en Valencia, Espa\u00f1a Direcci\u00f3n: 46002 Valencia Espa\u00f1a Embajador: Tel\u00e9fono: (+34) 96 342 7509 Fax: (+34) 96 351 9840 Email: Sitio web: valencia.consulado.gob.ec Horas de oficina: 08.30-15.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14012,15028,5314,13134],"tags":[12988],"class_list":["post-129637","post","type-post","status-publish","format-standard","hentry","category-consulado-general-ecuatoriano","category-consulado-general-en-espana","category-ecuador","category-espana","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129637"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129637"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129637\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}