{"id":129621,"date":"2019-09-01T09:15:19","date_gmt":"2019-09-01T09:15:19","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-filipinas-en-barcelona-%e2%80%8b%e2%80%8bespana\/"},"modified":"2019-09-01T09:15:19","modified_gmt":"2019-09-01T09:15:19","slug":"consulado-general-de-filipinas-en-barcelona-%e2%80%8b%e2%80%8bespana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-filipinas-en-barcelona-%e2%80%8b%e2%80%8bespana\/","title":{"rendered":"Consulado General de Filipinas en Barcelona, \u200b\u200bEspa\u00f1a"},"content":{"rendered":"<div id=\"trave-2113282833\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Filipinas en Barcelona, \u200b\u200bEspa\u00f1a<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nVia de les Corts Catalanes 594, 1-1<br \/>\nBarcelona<br \/>\nEspa\u00f1a<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Chona Abiertas Tenorio, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+34) 930 267 007<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> philconsulatebcn@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1045566001\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Filipinas en Barcelona, \u200b\u200bEspa\u00f1a Direcci\u00f3n: Via de les Corts Catalanes 594, 1-1 Barcelona Espa\u00f1a Embajador: Chona Abiertas Tenorio, C\u00f3nsul Honorario Tel\u00e9fono: (+34) 930 267 007 Fax: Email: philconsulatebcn@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13494,15028,13134,13195],"tags":[12988],"class_list":["post-129621","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-filipinas","category-consulado-general-en-espana","category-espana","category-filipinas","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129621"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129621"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129621\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}