{"id":129383,"date":"2019-09-01T09:13:07","date_gmt":"2019-09-01T09:13:07","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-luxemburgo-en-barcelona-%e2%80%8b%e2%80%8bespana\/"},"modified":"2019-09-01T09:13:07","modified_gmt":"2019-09-01T09:13:07","slug":"consulado-general-de-luxemburgo-en-barcelona-%e2%80%8b%e2%80%8bespana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-luxemburgo-en-barcelona-%e2%80%8b%e2%80%8bespana\/","title":{"rendered":"Consulado General de Luxemburgo en Barcelona, \u200b\u200bEspa\u00f1a"},"content":{"rendered":"<div id=\"trave-1826906362\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Luxemburgo en Barcelona, \u200b\u200bEspa\u00f1a<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n08006 Barcelona<br \/>\nEspa\u00f1a<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+34) 93 292 22 68<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.30 a 13.30 solo con cita<\/p>\n<div id=\"trave-583386074\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Luxemburgo en Barcelona, \u200b\u200bEspa\u00f1a Direcci\u00f3n: 08006 Barcelona Espa\u00f1a Embajador: Tel\u00e9fono: (+34) 93 292 22 68 Fax: Email: Sitio web: Horas de oficina: 09.30 a 13.30 solo con cita<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13637,15028,13134,13474],"tags":[12988],"class_list":["post-129383","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-luxemburgo","category-consulado-general-en-espana","category-espana","category-luxemburgo","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129383"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129383"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129383\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}