{"id":129069,"date":"2019-09-01T09:08:54","date_gmt":"2019-09-01T09:08:54","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-alemania-en-ciudad-del-cabo-sudafrica\/"},"modified":"2019-09-01T09:08:54","modified_gmt":"2019-09-01T09:08:54","slug":"consulado-general-de-alemania-en-ciudad-del-cabo-sudafrica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-alemania-en-ciudad-del-cabo-sudafrica\/","title":{"rendered":"Consulado General de Alemania en Ciudad del Cabo, Sud\u00e1frica"},"content":{"rendered":"<div id=\"trave-1616205423\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado alem\u00e1n en Ciudad del Cabo, Sud\u00e1frica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n4 Stirling Street<br \/>\nZonnebloem 7925<br \/>\nP.O.Box 4273<br \/>\nCiudad del Cabo 8000<br \/>\nSud\u00e1frica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Matthias Hansen, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+27) 21 405 3000<br \/>\n<strong>Fax:<\/strong> (+27) 21 421 0400<br \/>\n<strong>Email:<\/strong> info@kapstadt.diplo.de<br \/>\n<strong>Sitio web:<\/strong> www.capetown.diplo.de<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1737003749\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado alem\u00e1n en Ciudad del Cabo, Sud\u00e1frica Direcci\u00f3n: 4 Stirling Street Zonnebloem 7925 P.O.Box 4273 Ciudad del Cabo 8000 Sud\u00e1frica Embajador: Mr Matthias Hansen, C\u00f3nsul General Tel\u00e9fono: (+27) 21 405 3000 Fax: (+27) 21 421 0400 Email: info@kapstadt.diplo.de Sitio web: www.capetown.diplo.de Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,12992,15009,13251],"tags":[12988],"class_list":["post-129069","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulado-general-aleman","category-consulado-general-en-sudafrica","category-sudafrica","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129069"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=129069"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/129069\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=129069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=129069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=129069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}