{"id":128885,"date":"2019-09-01T09:06:30","date_gmt":"2019-09-01T09:06:30","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-espana-en-kosice-eslovaquia\/"},"modified":"2019-09-01T09:06:30","modified_gmt":"2019-09-01T09:06:30","slug":"consulado-de-espana-en-kosice-eslovaquia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-espana-en-kosice-eslovaquia\/","title":{"rendered":"Consulado de Espa\u00f1a en Kosice, Eslovaquia"},"content":{"rendered":"<div id=\"trave-3782901269\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado espa\u00f1ol en Kosice, Eslovaquia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nHutn\u00edcka, 1<br \/>\n040 01 Ko\u00c5\u00a1ice<br \/>\nEslovaquia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Daniel Luckanic, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+421) 55 799 7990<br \/>\n<strong>Fax:<\/strong> (+421) 55 799 9490<br \/>\n<strong>Email:<\/strong> oficina@es-consulhon.sk<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Martes a jueves: 09.00 a 12.00<\/p>\n<div id=\"trave-3785331773\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado espa\u00f1ol en Kosice, Eslovaquia Direcci\u00f3n: Hutn\u00edcka, 1 040 01 Ko\u00c5\u00a1ice Eslovaquia Embajador: Mr Daniel Luckanic, C\u00f3nsul Honorario Tel\u00e9fono: (+421) 55 799 7990 Fax: (+421) 55 799 9490 Email: oficina@es-consulhon.sk Sitio web: Horas de oficina: Martes a jueves: 09.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14988,13537,13236,13134],"tags":[12978],"class_list":["post-128885","post","type-post","status-publish","format-standard","hentry","category-consulados-en-eslovaquia","category-consulados-espanoles","category-eslovaquia","category-espana","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128885"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128885"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128885\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}