{"id":128857,"date":"2019-09-01T09:06:03","date_gmt":"2019-09-01T09:06:03","guid":{"rendered":"https:\/\/travelqa.com\/oficina-de-representacion-de-taiwan-en-bratislava-eslovaquia\/"},"modified":"2019-09-01T09:06:03","modified_gmt":"2019-09-01T09:06:03","slug":"oficina-de-representacion-de-taiwan-en-bratislava-eslovaquia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/oficina-de-representacion-de-taiwan-en-bratislava-eslovaquia\/","title":{"rendered":"Oficina de representaci\u00f3n de Taiw\u00e1n en Bratislava, Eslovaquia"},"content":{"rendered":"<div id=\"trave-575399432\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la oficina de representaci\u00f3n taiwanesa en Bratislava, Eslovaquia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMostova 2<br \/>\n81102 Bratislava<br \/>\nEslovaquia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Tseng, Larry, Representante<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+421) (2) 5825 3220 \/ 9<br \/>\n<strong>Fax:<\/strong> (+421) (2) 5825 3225<br \/>\n<strong>Email:<\/strong> svk@mofa.gov.tw<br \/>\n<strong>Sitio web:<\/strong> www.roc-taiwan.org\/sk\/<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-124480238\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la oficina de representaci\u00f3n taiwanesa en Bratislava, Eslovaquia Direcci\u00f3n: Mostova 2 81102 Bratislava Eslovaquia Embajador: Tseng, Larry, Representante Tel\u00e9fono: (+421) (2) 5825 3220 \/ 9 Fax: (+421) (2) 5825 3225 Email: svk@mofa.gov.tw Sitio web: www.roc-taiwan.org\/sk\/ Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13236,14991,13580,6641],"tags":[12981],"class_list":["post-128857","post","type-post","status-publish","format-standard","hentry","category-eslovaquia","category-oficinas-de-representacion-en-eslovaquia","category-oficinas-representativas-de-taiwan","category-taiwan","tag-oficina-representativa"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128857"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128857"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128857\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}