{"id":128632,"date":"2019-09-01T09:02:40","date_gmt":"2019-09-01T09:02:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-gabon-en-belgrado-serbia\/"},"modified":"2019-09-01T09:02:40","modified_gmt":"2019-09-01T09:02:40","slug":"consulado-de-gabon-en-belgrado-serbia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-gabon-en-belgrado-serbia\/","title":{"rendered":"Consulado de Gab\u00f3n en Belgrado, Serbia"},"content":{"rendered":"<div id=\"trave-2740315749\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Gab\u00f3n en Belgrado, Serbia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nLomina 48<br \/>\nBelgrado<br \/>\nSerbia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mrs Momira Radunovic, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+381) 11 3626 174<br \/>\n<strong>Fax:<\/strong> (+381) 11 3626 174<br \/>\n<strong>Email:<\/strong> konzulatrepublikegabon@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.00-16.00<\/p>\n<div id=\"trave-2696640105\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Gab\u00f3n en Belgrado, Serbia Direcci\u00f3n: Lomina 48 Belgrado Serbia Embajador: Mrs Momira Radunovic, C\u00f3nsul Honorario Tel\u00e9fono: (+381) 11 3626 174 Fax: (+381) 11 3626 174 Email: konzulatrepublikegabon@gmail.com Sitio web: Horas de oficina: 08.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14018,14964,5440,6450],"tags":[12978],"class_list":["post-128632","post","type-post","status-publish","format-standard","hentry","category-consulados-de-gabon","category-consulados-en-serbia","category-gabon","category-serbia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128632"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128632"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128632\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}