{"id":128628,"date":"2019-09-01T09:02:40","date_gmt":"2019-09-01T09:02:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-eslovaquia-en-nis-serbia\/"},"modified":"2019-09-01T09:02:40","modified_gmt":"2019-09-01T09:02:40","slug":"consulado-de-eslovaquia-en-nis-serbia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-eslovaquia-en-nis-serbia\/","title":{"rendered":"Consulado de Eslovaquia en Nis, Serbia"},"content":{"rendered":"<div id=\"trave-2634973526\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado eslovaco en Nis, Serbia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nOrlovica Pavla 28a<br \/>\n180 00 Salida<br \/>\nSerbia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Stela Jovanovic, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+381) 18 209 309<br \/>\n<strong>Fax:<\/strong> (+381) 18 209 240<br \/>\n<strong>Email:<\/strong> stela.jovanovic@gu.ni.rs<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-512167400\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado eslovaco en Nis, Serbia Direcci\u00f3n: Orlovica Pavla 28a 180 00 Salida Serbia Embajador: Stela Jovanovic, C\u00f3nsul Honorario Tel\u00e9fono: (+381) 18 209 309 Fax: (+381) 18 209 240 Email: stela.jovanovic@gu.ni.rs Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14964,13675,13236,6450],"tags":[12978],"class_list":["post-128628","post","type-post","status-publish","format-standard","hentry","category-consulados-en-serbia","category-consulados-eslovacos","category-eslovaquia","category-serbia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128628"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128628"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128628\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}