{"id":128435,"date":"2019-09-01T09:00:16","date_gmt":"2019-09-01T09:00:16","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-ghana-en-jeddah-arabia-saudita\/"},"modified":"2019-09-01T09:00:16","modified_gmt":"2019-09-01T09:00:16","slug":"consulado-general-de-ghana-en-jeddah-arabia-saudita","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-ghana-en-jeddah-arabia-saudita\/","title":{"rendered":"Consulado General de Ghana en Jeddah, Arabia Saudita"},"content":{"rendered":"<div id=\"trave-1165808878\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Ghana en Jeddah, Arabia Saudita<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCalle Jabal Al-Thawr Detr\u00e1s del Hospital Al-Jazeerah<br \/>\nVilla No.11, distrito de Musharrafh<br \/>\nP.O.Box 1657<br \/>\nJeddah 21441<br \/>\nArabia Saudita<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Mohammed Habib Idris Habib, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+966) (12) 660 1429<br \/>\n(+966) (12) 660 7545<br \/>\n<strong>Fax:<\/strong> (+966) (12) 662 2559<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3530550657\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Ghana en Jeddah, Arabia Saudita Direcci\u00f3n: Calle Jabal Al-Thawr Detr\u00e1s del Hospital Al-Jazeerah Villa No.11, distrito de Musharrafh P.O.Box 1657 Jeddah 21441 Arabia Saudita Embajador: Mr Mohammed Habib Idris Habib, C\u00f3nsul General Tel\u00e9fono: (+966) (12) 660 1429 (+966) (12) 660 7545 Fax: (+966) (12) 662 2559 Email: Sitio web: Horas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13157,14019,14952,5482],"tags":[12988],"class_list":["post-128435","post","type-post","status-publish","format-standard","hentry","category-arabia-saudita","category-consulado-general-de-ghana","category-consulado-general-en-arabia-saudita","category-ghana","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128435"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128435"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128435\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}