{"id":128432,"date":"2019-09-01T09:00:16","date_gmt":"2019-09-01T09:00:16","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-camerun-en-jeddah-arabia-saudita\/"},"modified":"2019-09-01T09:00:16","modified_gmt":"2019-09-01T09:00:16","slug":"consulado-general-de-camerun-en-jeddah-arabia-saudita","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-camerun-en-jeddah-arabia-saudita\/","title":{"rendered":"Consulado General de Camer\u00fan en Jeddah, Arabia Saudita"},"content":{"rendered":"<div id=\"trave-3841597927\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Camer\u00fan en Jeddah, Arabia Saudita<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nEdificio deldistrito Al-Nuzlah Al-Sharqiyah81 cerca del consulado de Yemen<br \/>\nP.O.Box 15517<br \/>\nJeddah 21454<br \/>\nArabia Saudita<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+966) (12) 680 4541<br \/>\n<strong>Fax:<\/strong> (+966) (12) 687 6320<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 15.00<\/p>\n<div id=\"trave-1203280685\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Camer\u00fan en Jeddah, Arabia Saudita Direcci\u00f3n: Edificio deldistrito Al-Nuzlah Al-Sharqiyah81 cerca del consulado de Yemen P.O.Box 15517 Jeddah 21454 Arabia Saudita Embajador: Tel\u00e9fono: (+966) (12) 680 4541 Fax: (+966) (12) 687 6320 Email: Sitio web: Horas de oficina: 09.00 a 15.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13157,13382,13942,14952],"tags":[12988],"class_list":["post-128432","post","type-post","status-publish","format-standard","hentry","category-arabia-saudita","category-camerun","category-consulado-general-de-camerun","category-consulado-general-en-arabia-saudita","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128432"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128432"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128432\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}