{"id":128430,"date":"2019-09-01T09:00:16","date_gmt":"2019-09-01T09:00:16","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-somalia-en-jeddah-arabia-saudita\/"},"modified":"2019-09-01T09:00:16","modified_gmt":"2019-09-01T09:00:16","slug":"consulado-general-de-somalia-en-jeddah-arabia-saudita","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-somalia-en-jeddah-arabia-saudita\/","title":{"rendered":"Consulado General de Somalia en Jeddah, Arabia Saudita"},"content":{"rendered":"<div id=\"trave-536103035\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado Somal\u00ed en Jeddah, Arabia Saudita<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAl lado del Postal saudita del distrito Almusa&#8217;idiyah<br \/>\nAl-Hamraa<br \/>\nP.O.Box 729<br \/>\nJeddah 21421<br \/>\nArabia Saudita<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+966) (12) 663 2108<br \/>\n(+966) (12) 663 1737<br \/>\n<strong>Fax:<\/strong> (+966) (12) 664 8834<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30-16.30<\/p>\n<div id=\"trave-2463830248\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado Somal\u00ed en Jeddah, Arabia Saudita Direcci\u00f3n: Al lado del Postal saudita del distrito Almusa&#8217;idiyah Al-Hamraa P.O.Box 729 Jeddah 21421 Arabia Saudita Embajador: Tel\u00e9fono: (+966) (12) 663 2108 (+966) (12) 663 1737 Fax: (+966) (12) 664 8834 Email: Sitio web: Horas de oficina: 08.30-16.30<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13157,14952,13756,6527],"tags":[12988],"class_list":["post-128430","post","type-post","status-publish","format-standard","hentry","category-arabia-saudita","category-consulado-general-en-arabia-saudita","category-consulado-general-somali","category-somalia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128430"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128430"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128430\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}