{"id":128428,"date":"2019-09-01T09:00:16","date_gmt":"2019-09-01T09:00:16","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-yemen-en-jeddah-arabia-saudita\/"},"modified":"2019-09-01T09:00:16","modified_gmt":"2019-09-01T09:00:16","slug":"consulado-general-de-yemen-en-jeddah-arabia-saudita","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-yemen-en-jeddah-arabia-saudita\/","title":{"rendered":"Consulado General de Yemen en Jeddah, Arabia Saudita"},"content":{"rendered":"<div id=\"trave-3323161446\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Yemen en Jeddah, Arabia Saudita<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPO Box 2793<br \/>\nJeddah 21461<br \/>\nArabia Saudita<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+966) (12) 689 8555<br \/>\n<strong>Fax:<\/strong> (+966) (12) 689 4567<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> www.yemenconsulatejeddah.com<\/p>\n<p><strong>Horas de oficina:<\/strong> 08.00-14.00<\/p>\n<div id=\"trave-2575108155\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Yemen en Jeddah, Arabia Saudita Direcci\u00f3n: PO Box 2793 Jeddah 21461 Arabia Saudita Embajador: Tel\u00e9fono: (+966) (12) 689 8555 Fax: (+966) (12) 689 4567 Email: Sitio web: www.yemenconsulatejeddah.com Horas de oficina: 08.00-14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13157,14367,14952,6889],"tags":[12988],"class_list":["post-128428","post","type-post","status-publish","format-standard","hentry","category-arabia-saudita","category-consulado-general-de-yemen","category-consulado-general-en-arabia-saudita","category-yemen","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128428"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128428"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128428\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}