{"id":128402,"date":"2019-09-01T08:59:56","date_gmt":"2019-09-01T08:59:56","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-noruega-en-jeddah-arabia-saudita\/"},"modified":"2019-09-01T08:59:56","modified_gmt":"2019-09-01T08:59:56","slug":"consulado-general-de-noruega-en-jeddah-arabia-saudita","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-noruega-en-jeddah-arabia-saudita\/","title":{"rendered":"Consulado General de Noruega en Jeddah, Arabia Saudita"},"content":{"rendered":"<div id=\"trave-4000975467\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Noruega en Jeddah, Arabia Saudita<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nJeddah 21425<br \/>\nArabia Saudita<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+966) (12) 661 1222 &#8211; ext. 300<br \/>\n<strong>Fax:<\/strong> (+966) (12) 665 5611<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 15.00<\/p>\n<div id=\"trave-1100630233\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Noruega en Jeddah, Arabia Saudita Direcci\u00f3n: Jeddah 21425 Arabia Saudita Embajador: Tel\u00e9fono: (+966) (12) 661 1222 &#8211; ext. 300 Fax: (+966) (12) 665 5611 Email: Sitio web: Horas de oficina: 09.00 a 15.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13157,13261,14952,13153],"tags":[12988],"class_list":["post-128402","post","type-post","status-publish","format-standard","hentry","category-arabia-saudita","category-consulado-general-de-noruega","category-consulado-general-en-arabia-saudita","category-noruega","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128402"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128402"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128402\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}