{"id":128233,"date":"2019-09-01T08:58:06","date_gmt":"2019-09-01T08:58:06","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-angola-en-santo-tome-santo-tome-y-principe\/"},"modified":"2019-09-01T08:58:06","modified_gmt":"2019-09-01T08:58:06","slug":"embajada-de-angola-en-santo-tome-santo-tome-y-principe","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-angola-en-santo-tome-santo-tome-y-principe\/","title":{"rendered":"Embajada de Angola en Santo Tom\u00e9, Santo Tom\u00e9 y Pr\u00edncipe"},"content":{"rendered":"<div id=\"trave-2343641995\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Angola en Santo Tom\u00e9, Santo Tom\u00e9 y Pr\u00edncipe<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAv.das Nacoes Unidas No.200<br \/>\nSanto<br \/>\nTom\u00e9 Santo Tom\u00e9 y Pr\u00edncipe<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Pedro Fernando Mavunza, Embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+239) 224 3802<br \/>\n<strong>Fax:<\/strong> (+239) 224 3802<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2370169867\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Angola en Santo Tom\u00e9, Santo Tom\u00e9 y Pr\u00edncipe Direcci\u00f3n: Av.das Nacoes Unidas No.200 Santo Tom\u00e9 Santo Tom\u00e9 y Pr\u00edncipe Embajador: Sr. Pedro Fernando Mavunza, Embajador Tel\u00e9fono: (+239) 224 3802 Fax: (+239) 224 3802 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4793,13381,14951,13490],"tags":[12975],"class_list":["post-128233","post","type-post","status-publish","format-standard","hentry","category-angola","category-embajadas-de-angola","category-embajadas-en-santo-tome-y-principe","category-santo-tome-y-principe","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128233"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128233"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128233\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}