{"id":128171,"date":"2019-09-01T08:56:26","date_gmt":"2019-09-01T08:56:26","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-venezuela-en-castries-santa-lucia\/"},"modified":"2019-09-01T08:56:26","modified_gmt":"2019-09-01T08:56:26","slug":"embajada-de-venezuela-en-castries-santa-lucia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-venezuela-en-castries-santa-lucia\/","title":{"rendered":"Embajada de Venezuela en Castries, Santa Luc\u00eda"},"content":{"rendered":"<div id=\"trave-1667651799\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Venezuela en Castries, Santa Luc\u00eda<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCasa Vigie<br \/>\nP.O.Box 494<br \/>\nCastries<br \/>\nSanta Luc\u00eda<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Leiff Escalona, \u200b\u200bEmbajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1 758) 452-4033<br \/>\n<strong>Fax:<\/strong> (+1 758) 453-6747<br \/>\n<strong>Email:<\/strong> vembassy@candw.lc<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-841764611\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Venezuela en Castries, Santa Luc\u00eda Direcci\u00f3n: Casa Vigie P.O.Box 494 Castries Santa Luc\u00eda Embajador: Leiff Escalona, \u200b\u200bEmbajador Tel\u00e9fono: (+1 758) 452-4033 Fax: (+1 758) 453-6747 Email: vembassy@candw.lc Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14930,13370,13917,6866],"tags":[12975],"class_list":["post-128171","post","type-post","status-publish","format-standard","hentry","category-embajadas-en-santa-lucia","category-embajadas-venezolanas","category-santa-lucia","category-venezuela","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128171"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128171"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128171\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}