{"id":128004,"date":"2019-09-01T08:53:38","date_gmt":"2019-09-01T08:53:38","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-monaco-en-moscu-rusia\/"},"modified":"2019-09-01T08:53:38","modified_gmt":"2019-09-01T08:53:38","slug":"consulado-general-de-monaco-en-moscu-rusia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-monaco-en-moscu-rusia\/","title":{"rendered":"Consulado General de M\u00f3naco en Mosc\u00fa, Rusia"},"content":{"rendered":"<div id=\"trave-3341127941\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado Monegasco en Mosc\u00fa, Rusia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n27, murci\u00e9lago.3, Rue Lyusinovskaya<br \/>\n115093 Mosc\u00fa<br \/>\nRusia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+7) 499 236 12 09<br \/>\n<strong>Fax:<\/strong> (+7) 495 956 65 87<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-722596785\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado Monegasco en Mosc\u00fa, Rusia Direcci\u00f3n: 27, murci\u00e9lago.3, Rue Lyusinovskaya 115093 Mosc\u00fa Rusia Embajador: Tel\u00e9fono: (+7) 499 236 12 09 Fax: (+7) 495 956 65 87 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14901,13874,6017,12973],"tags":[12988],"class_list":["post-128004","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-rusia","category-consulado-general-monegasco","category-monaco","category-rusia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128004"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=128004"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/128004\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=128004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=128004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=128004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}