{"id":127994,"date":"2019-09-01T08:53:20","date_gmt":"2019-09-01T08:53:20","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-japon-en-yuzhno-sakhalinsk-rusia\/"},"modified":"2019-09-01T08:53:20","modified_gmt":"2019-09-01T08:53:20","slug":"consulado-general-de-japon-en-yuzhno-sakhalinsk-rusia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-japon-en-yuzhno-sakhalinsk-rusia\/","title":{"rendered":"Consulado General de Jap\u00f3n en Yuzhno-Sakhalinsk, Rusia"},"content":{"rendered":"<div id=\"trave-3947581983\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado japon\u00e9s en Yuzhno-Sakhalinsk, Rusia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nKommunisticheskiy Prospekt, 18<br \/>\nYuzhno-Sakhalinsk 693010<br \/>\nRusia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Ruiti Hirano, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+7) (4242) 725 530<br \/>\n(+7) (4242) 726 055<br \/>\n<strong>Fax:<\/strong> (+7) (4242) 725 531<br \/>\n<strong>Email:<\/strong> sakhlinjp1@ys.mofa.go.jp<br \/>\nvisa-2@ys.mofa.go.jp<br \/>\n<strong>Sitio web:<\/strong> www.sakhalin.ru.emb-japan.go.jp<\/p>\n<p><strong>Horas de oficina:<\/strong> 09:15 &#8211; 12:30 y 13:30 &#8211; 18:00<\/p>\n<div id=\"trave-2919141239\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado japon\u00e9s en Yuzhno-Sakhalinsk, Rusia Direcci\u00f3n: Kommunisticheskiy Prospekt, 18 Yuzhno-Sakhalinsk 693010 Rusia Embajador: Ruiti Hirano, C\u00f3nsul General Tel\u00e9fono: (+7) (4242) 725 530 (+7) (4242) 726 055 Fax: (+7) (4242) 725 531 Email: sakhlinjp1@ys.mofa.go.jp visa-2@ys.mofa.go.jp Sitio web: www.sakhalin.ru.emb-japan.go.jp Horas de oficina: 09:15 &#8211; 12:30 y 13:30 &#8211; 18:00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14901,13561,10869,12973],"tags":[12988],"class_list":["post-127994","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-rusia","category-consulado-general-japones","category-japon","category-rusia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127994"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=127994"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127994\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=127994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=127994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=127994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}