{"id":127948,"date":"2019-09-01T08:53:00","date_gmt":"2019-09-01T08:53:00","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-azerbaiyan-en-ekaterimburgo-rusia\/"},"modified":"2019-09-01T08:53:00","modified_gmt":"2019-09-01T08:53:00","slug":"consulado-general-de-azerbaiyan-en-ekaterimburgo-rusia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-azerbaiyan-en-ekaterimburgo-rusia\/","title":{"rendered":"Consulado General de Azerbaiy\u00e1n en Ekaterimburgo, Rusia"},"content":{"rendered":"<div id=\"trave-1103642009\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Azerbaiy\u00e1n en Ekaterimburgo, Rusia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n620075 Ekaterimburgo<br \/>\nRusia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+7) (323) 371 55 32 \/ 17<br \/>\n<strong>Fax:<\/strong> (+7) (343) 371 55 59<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3414452863\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Azerbaiy\u00e1n en Ekaterimburgo, Rusia Direcci\u00f3n: 620075 Ekaterimburgo Rusia Embajador: Tel\u00e9fono: (+7) (323) 371 55 32 \/ 17 Fax: (+7) (343) 371 55 59 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13332,14345,14901,12973],"tags":[12988],"class_list":["post-127948","post","type-post","status-publish","format-standard","hentry","category-azerbaiyan","category-consulado-general-de-azerbaiyan","category-consulado-general-en-rusia","category-rusia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127948"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=127948"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127948\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=127948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=127948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=127948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}