{"id":127648,"date":"2019-09-01T08:49:39","date_gmt":"2019-09-01T08:49:39","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-alemania-en-timisoara-rumania\/"},"modified":"2019-09-01T08:49:39","modified_gmt":"2019-09-01T08:49:39","slug":"consulado-general-de-alemania-en-timisoara-rumania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-alemania-en-timisoara-rumania\/","title":{"rendered":"Consulado General de Alemania en Timisoara, Rumania"},"content":{"rendered":"<div id=\"trave-771525198\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado alem\u00e1n en Timisoara, Rumania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nSplaiul Tudor Vladimirescu no.10<br \/>\n300195 Timisoara<br \/>\nRuman\u00eda<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Ralf Krautkramer, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+40) 256 309 800<br \/>\n<strong>Fax:<\/strong> (+40) 256 490 487<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> www.temeswar.diplo.de<br \/>\nwww.timisoara.diplo.de<\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30-11.30<\/p>\n<div id=\"trave-1951069372\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado alem\u00e1n en Timisoara, Rumania Direcci\u00f3n: Splaiul Tudor Vladimirescu no.10 300195 Timisoara Ruman\u00eda Embajador: Mr Ralf Krautkramer, C\u00f3nsul General Tel\u00e9fono: (+40) 256 309 800 Fax: (+40) 256 490 487 Email: Sitio web: www.temeswar.diplo.de www.timisoara.diplo.de Horas de oficina: 08.30-11.30<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,12992,14897,13166],"tags":[12988],"class_list":["post-127648","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulado-general-aleman","category-consulado-general-en-rumania","category-rumania","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127648"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=127648"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127648\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=127648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=127648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=127648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}