{"id":127435,"date":"2019-09-01T08:47:13","date_gmt":"2019-09-01T08:47:13","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-la-republica-de-corea-en-san-juan-puerto-rico\/"},"modified":"2019-09-01T08:47:13","modified_gmt":"2019-09-01T08:47:13","slug":"consulado-de-la-republica-de-corea-en-san-juan-puerto-rico","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-la-republica-de-corea-en-san-juan-puerto-rico\/","title":{"rendered":"Consulado de la Rep\u00fablica de Corea en San Juan, Puerto Rico"},"content":{"rendered":"<div id=\"trave-3368100927\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Corea del Sur en San Juan, Puerto Rico<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMCS Plaza, Piso 10<br \/>\n255 Ave.Ponce de Le\u00f3n<br \/>\nP.O.Box 364148<br \/>\nSan Juan 00917<br \/>\nPuerto Rico<br \/>\n<strong><br \/>\nEmbajador:<\/strong> H\u00e9ctor Reichard, Jr., C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1 787) 777-8888<br \/>\n(+1 787) 777-8801<br \/>\n<strong>Fax:<\/strong> (+1 787) 765-4225<br \/>\n<strong>Email:<\/strong> reichard@reichardescalera.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-53438649\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Corea del Sur en San Juan, Puerto Rico Direcci\u00f3n: MCS Plaza, Piso 10 255 Ave.Ponce de Le\u00f3n P.O.Box 364148 San Juan 00917 Puerto Rico Embajador: H\u00e9ctor Reichard, Jr., C\u00f3nsul Honorario Tel\u00e9fono: (+1 787) 777-8888 (+1 787) 777-8801 Fax: (+1 787) 765-4225 Email: reichard@reichardescalera.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13265,14886,13151,6314],"tags":[12978],"class_list":["post-127435","post","type-post","status-publish","format-standard","hentry","category-consulados-de-corea-del-sur","category-consulados-en-puerto-rico","category-corea-del-sur-republica-de","category-puerto-rico","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127435"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=127435"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127435\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=127435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=127435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=127435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}