{"id":127345,"date":"2019-09-01T08:46:26","date_gmt":"2019-09-01T08:46:26","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-angola-en-faro-portugal\/"},"modified":"2019-09-01T08:46:26","modified_gmt":"2019-09-01T08:46:26","slug":"consulado-general-de-angola-en-faro-portugal","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-angola-en-faro-portugal\/","title":{"rendered":"Consulado General de Angola en Faro, Portugal"},"content":{"rendered":"<div id=\"trave-3973892063\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Angola en Faro, Portugal<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRua de Moambique (paralelo \u00c3 Av. Calouste Gulbenkian)<br \/>\nLote Q 1\u00ba Esquerdo<br \/>\n8005-203 Faro<br \/>\nPortugal<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Lu\u00eds Filipe Alonso Galiano, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+351) 289 897 100<br \/>\n(+351) 289 895 622<br \/>\n<strong>Fax:<\/strong> (+351) 289 897 108 \/ 9<br \/>\n<strong>Email:<\/strong> geral@consuladogeralangola-faro.pt<br \/>\n<strong>Sitio web:<\/strong> www.consuladogeralangola-faro.pt<\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 &#8211; 13.00 y 14.30 &#8211; 16.30<\/p>\n<div id=\"trave-1731992795\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Angola en Faro, Portugal Direcci\u00f3n: Rua de Moambique (paralelo \u00c3 Av. Calouste Gulbenkian) Lote Q 1\u00ba Esquerdo 8005-203 Faro Portugal Embajador: Lu\u00eds Filipe Alonso Galiano, C\u00f3nsul General Tel\u00e9fono: (+351) 289 897 100 (+351) 289 895 622 Fax: (+351) 289 897 108 \/ 9 Email: geral@consuladogeralangola-faro.pt Sitio web: www.consuladogeralangola-faro.pt Horas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4793,14002,14881,6301],"tags":[12988],"class_list":["post-127345","post","type-post","status-publish","format-standard","hentry","category-angola","category-consulado-general-de-angola","category-consulado-general-en-portugal","category-portugal","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127345"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=127345"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127345\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=127345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=127345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=127345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}