{"id":127299,"date":"2019-09-01T08:45:54","date_gmt":"2019-09-01T08:45:54","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-dinamarca-en-funchal-portugal\/"},"modified":"2019-09-01T08:45:54","modified_gmt":"2019-09-01T08:45:54","slug":"consulado-de-dinamarca-en-funchal-portugal","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-dinamarca-en-funchal-portugal\/","title":{"rendered":"Consulado de Dinamarca en Funchal, Portugal"},"content":{"rendered":"<div id=\"trave-3217422861\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado dan\u00e9s en Funchal, Portugal<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n9000-642 Funchal<br \/>\nPortugal<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Ricardo Carlos Legge Dias do Nascimento, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+351) 291 742 596<br \/>\n<strong>Fax:<\/strong> (+351) 291 742 596<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00-18.00<\/p>\n<div id=\"trave-949134841\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado dan\u00e9s en Funchal, Portugal Direcci\u00f3n: 9000-642 Funchal Portugal Embajador: Mr Ricardo Carlos Legge Dias do Nascimento, C\u00f3nsul Honorario Tel\u00e9fono: (+351) 291 742 596 Fax: (+351) 291 742 596 Email: Sitio web: Horas de oficina: 09.00-18.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13177,14880,13136,6301],"tags":[12978],"class_list":["post-127299","post","type-post","status-publish","format-standard","hentry","category-consulados-daneses","category-consulados-en-portugal","category-dinamarca","category-portugal","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127299"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=127299"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127299\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=127299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=127299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=127299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}