{"id":127035,"date":"2019-09-01T08:43:14","date_gmt":"2019-09-01T08:43:14","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-reino-unido-en-szczecin-polonia\/"},"modified":"2019-09-01T08:43:14","modified_gmt":"2019-09-01T08:43:14","slug":"consulado-de-reino-unido-en-szczecin-polonia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-reino-unido-en-szczecin-polonia\/","title":{"rendered":"Consulado de Reino Unido en Szczecin, Polonia"},"content":{"rendered":"<div id=\"trave-1658652977\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado brit\u00e1nico en Szczecin, Polonia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nSzczecin<br \/>\nPolonia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Ryszard Jacek Karger, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> www.gov.uk\/government\/world\/poland<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2164860536\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado brit\u00e1nico en Szczecin, Polonia Direcci\u00f3n: Szczecin Polonia Embajador: Mr Ryszard Jacek Karger, C\u00f3nsul Honorario Tel\u00e9fono: Fax: Email: Sitio web: www.gov.uk\/government\/world\/poland Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13484,14872,13263,13069],"tags":[12978],"class_list":["post-127035","post","type-post","status-publish","format-standard","hentry","category-consulados-britanicos","category-consulados-en-polonia","category-polonia","category-reino-unido","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127035"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=127035"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/127035\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=127035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=127035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=127035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}