{"id":126793,"date":"2019-09-01T08:40:56","date_gmt":"2019-09-01T08:40:56","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-ecuador-en-manila-filipinas\/"},"modified":"2019-09-01T08:40:56","modified_gmt":"2019-09-01T08:40:56","slug":"consulado-general-de-ecuador-en-manila-filipinas","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-ecuador-en-manila-filipinas\/","title":{"rendered":"Consulado General de Ecuador en Manila, Filipinas"},"content":{"rendered":"<div id=\"trave-1332461473\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado ecuatoriano en Manila, Filipinas<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n39 Plaza Drive, Rockwell Center<br \/>\nMakati City<br \/>\nManila<br \/>\nFilipinas<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+63) (2) 8700 100<br \/>\n(+63) (2) 8700 575<br \/>\n<strong>Fax:<\/strong> (+63) (2) 8700 510<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2895150484\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado ecuatoriano en Manila, Filipinas Direcci\u00f3n: 39 Plaza Drive, Rockwell Center Makati City Manila Filipinas Embajador: Tel\u00e9fono: (+63) (2) 8700 100 (+63) (2) 8700 575 Fax: (+63) (2) 8700 510 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14012,14865,5314,13195],"tags":[12988],"class_list":["post-126793","post","type-post","status-publish","format-standard","hentry","category-consulado-general-ecuatoriano","category-consulado-general-en-filipinas","category-ecuador","category-filipinas","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126793"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126793"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126793\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}