{"id":126711,"date":"2019-09-01T08:40:02","date_gmt":"2019-09-01T08:40:02","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-arabia-saudita-en-lima-peru\/"},"modified":"2019-09-01T08:40:02","modified_gmt":"2019-09-01T08:40:02","slug":"embajada-de-arabia-saudita-en-lima-peru","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-arabia-saudita-en-lima-peru\/","title":{"rendered":"Embajada de Arabia Saudita en Lima, Per\u00fa"},"content":{"rendered":"<div id=\"trave-926883156\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Arabia Saudita en Lima, Per\u00fa<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nLima<br \/>\nPeru<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Hamoud T. Almutairi, Encargado de Negocios ai<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+51) 1 222-4959<br \/>\n<strong>Fax:<\/strong> (+51) 1 222-4959<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00-16.00<\/p>\n<div id=\"trave-2392708551\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Arabia Saudita en Lima, Per\u00fa Direcci\u00f3n: Lima Peru Embajador: Hamoud T. Almutairi, Encargado de Negocios ai Tel\u00e9fono: (+51) 1 222-4959 Fax: (+51) 1 222-4959 Email: Sitio web: Horas de oficina: 09.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13157,13159,14859,6261],"tags":[12975],"class_list":["post-126711","post","type-post","status-publish","format-standard","hentry","category-arabia-saudita","category-embajadas-de-arabia-saudita","category-embajadas-en-peru","category-peru","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126711"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126711"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126711\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}