{"id":126704,"date":"2019-09-01T08:40:02","date_gmt":"2019-09-01T08:40:02","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-chile-en-tacna-peru\/"},"modified":"2019-09-01T08:40:02","modified_gmt":"2019-09-01T08:40:02","slug":"consulado-general-de-chile-en-tacna-peru","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-chile-en-tacna-peru\/","title":{"rendered":"Consulado General de Chile en Tacna, Per\u00fa"},"content":{"rendered":"<div id=\"trave-3555453760\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Chile en Tacna, Per\u00fa<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nTacna<br \/>\nPeru<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Gustavo Alberto D\u00edaz Hidalgo, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+51) 52 424 391<br \/>\n(+51) 52 423 081<br \/>\n<strong>Fax:<\/strong> (+51) 52 424 391<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30 a 13.00<\/p>\n<div id=\"trave-2063668395\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Chile en Tacna, Per\u00fa Direcci\u00f3n: Tacna Peru Embajador: Sr. Gustavo Alberto D\u00edaz Hidalgo, C\u00f3nsul General Tel\u00e9fono: (+51) 52 424 391 (+51) 52 423 081 Fax: (+51) 52 424 391 Email: Sitio web: Horas de oficina: 08.30 a 13.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5134,13589,14860,6261],"tags":[12988],"class_list":["post-126704","post","type-post","status-publish","format-standard","hentry","category-chile","category-consulado-general-de-chile","category-consulado-general-en-peru","category-peru","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126704"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126704"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126704\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}