{"id":126546,"date":"2019-09-01T08:38:10","date_gmt":"2019-09-01T08:38:10","guid":{"rendered":"https:\/\/travelqa.com\/nunciatura-apostolica-de-la-santa-sede-en-asuncion-paraguay\/"},"modified":"2019-09-01T08:38:10","modified_gmt":"2019-09-01T08:38:10","slug":"nunciatura-apostolica-de-la-santa-sede-en-asuncion-paraguay","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/nunciatura-apostolica-de-la-santa-sede-en-asuncion-paraguay\/","title":{"rendered":"Nunciatura Apost\u00f3lica de la Santa Sede en Asunci\u00f3n, Paraguay"},"content":{"rendered":"<div id=\"trave-4089629170\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Asunci\u00f3n, Paraguay<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nen 25 Mayo y Caballero<br \/>\nCasilla 83<br \/>\nAsunci\u00f3n<br \/>\nParaguay<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Eliseo Antonio Ariotti, Nuncio Apost\u00f3lico<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+595) (21) 212 590<br \/>\n(+595) (21) 211 037<br \/>\n<strong>Fax:<\/strong> (+595) (21) 212 590<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2555022821\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Asunci\u00f3n, Paraguay Direcci\u00f3n: en 25 Mayo y Caballero Casilla 83 Asunci\u00f3n Paraguay Embajador: Eliseo Antonio Ariotti, Nuncio Apost\u00f3lico Tel\u00e9fono: (+595) (21) 212 590 (+595) (21) 211 037 Fax: (+595) (21) 212 590 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14856,6252,13258,13260],"tags":[13262],"class_list":["post-126546","post","type-post","status-publish","format-standard","hentry","category-nunciatura-apostolica-en-paraguay","category-paraguay","category-santa-sede","category-santa-sede-nunciatura-apostolica","tag-nunciatura-apostolica"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126546"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126546"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126546\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}