{"id":126510,"date":"2019-09-01T08:37:48","date_gmt":"2019-09-01T08:37:48","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-finlandia-en-asuncion-paraguay\/"},"modified":"2019-09-01T08:37:48","modified_gmt":"2019-09-01T08:37:48","slug":"consulado-de-finlandia-en-asuncion-paraguay","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-finlandia-en-asuncion-paraguay\/","title":{"rendered":"Consulado de Finlandia en Asunci\u00f3n, Paraguay"},"content":{"rendered":"<div id=\"trave-3443717334\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado finland\u00e9s en Asunci\u00f3n, Paraguay<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nEdificio Empresas Pallares<br \/>\nBrasil 123<br \/>\nCasilia de Correo 1674<br \/>\nAsunci\u00f3n<br \/>\nParaguay<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Pablo Livieres Guggiari, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+595) 21 221 477<br \/>\n<strong>Fax:<\/strong> (+595) 8 226 336<br \/>\n<strong>Email:<\/strong> carlosss@schauman.com.py<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-852549582\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado finland\u00e9s en Asunci\u00f3n, Paraguay Direcci\u00f3n: Edificio Empresas Pallares Brasil 123 Casilia de Correo 1674 Asunci\u00f3n Paraguay Embajador: Pablo Livieres Guggiari, C\u00f3nsul Honorario Tel\u00e9fono: (+595) 21 221 477 Fax: (+595) 8 226 336 Email: carlosss@schauman.com.py Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14854,13285,12998,6252],"tags":[12978],"class_list":["post-126510","post","type-post","status-publish","format-standard","hentry","category-consulados-en-paraguay","category-consulados-finlandeses","category-finlandia","category-paraguay","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126510"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126510"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126510\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}