{"id":126440,"date":"2019-09-01T08:36:29","date_gmt":"2019-09-01T08:36:29","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-peru-en-colon-panama\/"},"modified":"2019-09-01T08:36:29","modified_gmt":"2019-09-01T08:36:29","slug":"consulado-de-peru-en-colon-panama","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-peru-en-colon-panama\/","title":{"rendered":"Consulado de Per\u00fa en Col\u00f3n, Panam\u00e1"},"content":{"rendered":"<div id=\"trave-2165966050\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado peruano en Col\u00f3n, Panam\u00e1<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBodegas Farmzaona Zona de Procesamiento Mz.<br \/>\n5 Calle del Melia<br \/>\nCol\u00f3n<br \/>\nPanam\u00e1<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Giovanni Ferrari Francucci, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+507) 430 3957<br \/>\n<strong>Fax:<\/strong> (+507) 430 3957<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.00 a 12.00<\/p>\n<div id=\"trave-57107063\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado peruano en Col\u00f3n, Panam\u00e1 Direcci\u00f3n: Bodegas Farmzaona Zona de Procesamiento Mz. 5 Calle del Melia Col\u00f3n Panam\u00e1 Embajador: Mr Giovanni Ferrari Francucci, C\u00f3nsul Honorario Tel\u00e9fono: (+507) 430 3957 Fax: (+507) 430 3957 Email: Sitio web: Horas de oficina: 08.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14843,13563,6231,6261],"tags":[12978],"class_list":["post-126440","post","type-post","status-publish","format-standard","hentry","category-consulados-en-panama","category-consulados-peruanos","category-panama","category-peru","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126440"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126440"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126440\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}