{"id":126307,"date":"2019-09-01T08:33:15","date_gmt":"2019-09-01T08:33:15","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-peru-en-islamabad-pakistan\/"},"modified":"2019-09-01T08:33:15","modified_gmt":"2019-09-01T08:33:15","slug":"consulado-de-peru-en-islamabad-pakistan","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-peru-en-islamabad-pakistan\/","title":{"rendered":"Consulado de Per\u00fa en Islamabad, Pakist\u00e1n"},"content":{"rendered":"<div id=\"trave-239478894\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado peruano en Islamabad, Pakist\u00e1n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nIslamabad<br \/>\nPakist\u00e1n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Tariq Khan Afridi, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 14.00<\/p>\n<div id=\"trave-1381121188\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado peruano en Islamabad, Pakist\u00e1n Direcci\u00f3n: Islamabad Pakist\u00e1n Embajador: Tariq Khan Afridi, C\u00f3nsul Honorario Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina: 09.00 a 14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14803,13563,6205,6261],"tags":[12978],"class_list":["post-126307","post","type-post","status-publish","format-standard","hentry","category-consulados-en-pakistan","category-consulados-peruanos","category-pakistan","category-peru","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126307"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126307"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126307\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}