{"id":126087,"date":"2019-09-01T08:31:00","date_gmt":"2019-09-01T08:31:00","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-monaco-en-karachi-pakistan\/"},"modified":"2019-09-01T08:31:00","modified_gmt":"2019-09-01T08:31:00","slug":"consulado-de-monaco-en-karachi-pakistan","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-monaco-en-karachi-pakistan\/","title":{"rendered":"Consulado de M\u00f3naco en Karachi, Pakist\u00e1n"},"content":{"rendered":"<div id=\"trave-2039172850\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado monegasco en Karachi, Pakist\u00e1n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nGulzaman 2 Sunnyside Road<br \/>\nCivil Lines<br \/>\nKarachi 4<br \/>\nPakist\u00e1n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mrs Charmaine Hidayatullah, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+92) 21.34.31.43.46 or<br \/>\n(+92) 21.35.62.28.16<br \/>\n<strong>Fax:<\/strong> (+92) 21.34.54.85.75 or<br \/>\n(+92) 21.35.62.28.16<br \/>\n<strong>Email:<\/strong> hidwat@gmail.com<br \/>\nch.hedaya@hotmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1328679405\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado monegasco en Karachi, Pakist\u00e1n Direcci\u00f3n: Gulzaman 2 Sunnyside Road Civil Lines Karachi 4 Pakist\u00e1n Embajador: Mrs Charmaine Hidayatullah, C\u00f3nsul Honorario Tel\u00e9fono: (+92) 21.34.31.43.46 or (+92) 21.35.62.28.16 Fax: (+92) 21.34.54.85.75 or (+92) 21.35.62.28.16 Email: hidwat@gmail.com ch.hedaya@hotmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14803,13541,6017,6205],"tags":[12978],"class_list":["post-126087","post","type-post","status-publish","format-standard","hentry","category-consulados-en-pakistan","category-consulados-monegascos","category-monaco","category-pakistan","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126087"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=126087"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/126087\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=126087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=126087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=126087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}