{"id":125950,"date":"2019-09-01T08:29:40","date_gmt":"2019-09-01T08:29:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-bangladesh-en-bergen-noruega\/"},"modified":"2019-09-01T08:29:40","modified_gmt":"2019-09-01T08:29:40","slug":"consulado-general-de-bangladesh-en-bergen-noruega","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-bangladesh-en-bergen-noruega\/","title":{"rendered":"Consulado General de Bangladesh en Bergen, Noruega"},"content":{"rendered":"<div id=\"trave-340642920\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Bangladesh en Bergen, Noruega<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n\u00c3\u02dcstre Hopsveg<br \/>\n5043 Hop<br \/>\nBergen<br \/>\nNoruega<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Eilif Dosen, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+47) 55-575 202<br \/>\n(+47) 55-913 749<br \/>\n<strong>Fax:<\/strong> (+47) 55-575 281<br \/>\n<strong>Email:<\/strong> eilid@online.no<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-150774677\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Bangladesh en Bergen, Noruega Direcci\u00f3n: \u00c3\u02dcstre Hopsveg 5043 Hop Bergen Noruega Embajador: Eilif Dosen, C\u00f3nsul General Honorario Tel\u00e9fono: (+47) 55-575 202 (+47) 55-913 749 Fax: (+47) 55-575 281 Email: eilid@online.no Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4892,13703,14795,13153],"tags":[12988],"class_list":["post-125950","post","type-post","status-publish","format-standard","hentry","category-bangladesh","category-consulado-general-de-bangladesh","category-consulado-general-en-noruega","category-noruega","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/125950"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=125950"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/125950\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=125950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=125950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=125950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}