{"id":125449,"date":"2019-09-01T08:23:23","date_gmt":"2019-09-01T08:23:23","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-dinamarca-en-managua-nicaragua\/"},"modified":"2019-09-01T08:23:23","modified_gmt":"2019-09-01T08:23:23","slug":"consulado-general-de-dinamarca-en-managua-nicaragua","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-dinamarca-en-managua-nicaragua\/","title":{"rendered":"Consulado General de Dinamarca en Managua, Nicaragua"},"content":{"rendered":"<div id=\"trave-3740706160\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado dan\u00e9s en Managua, Nicaragua<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCalle Atraverzada, francia Bancentro<br \/>\nApartado Postal 4942<br \/>\nGranada<br \/>\nNicaragua<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Peder Kolind, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+505) 888 942 72<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00-12.00<\/p>\n<div id=\"trave-3056491792\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado dan\u00e9s en Managua, Nicaragua Direcci\u00f3n: Calle Atraverzada, francia Bancentro Apartado Postal 4942 Granada Nicaragua Embajador: Mr Peder Kolind, C\u00f3nsul General Honorario Tel\u00e9fono: (+505) 888 942 72 Fax: Email: Sitio web: Horas de oficina: 10.00-12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13712,14763,13136,6129],"tags":[12988],"class_list":["post-125449","post","type-post","status-publish","format-standard","hentry","category-consulado-general-danes","category-consulado-general-en-nicaragua","category-dinamarca","category-nicaragua","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/125449"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=125449"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/125449\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=125449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=125449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=125449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}