{"id":124883,"date":"2019-09-01T08:16:38","date_gmt":"2019-09-01T08:16:38","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-la-republica-del-congo-en-windhoek-namibia\/"},"modified":"2019-09-01T08:16:38","modified_gmt":"2019-09-01T08:16:38","slug":"embajada-de-la-republica-del-congo-en-windhoek-namibia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-la-republica-del-congo-en-windhoek-namibia\/","title":{"rendered":"Embajada de la Rep\u00fablica del Congo en Windhoek, Namibia"},"content":{"rendered":"<div id=\"trave-3010991100\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada congole\u00f1a en Windhoek, Namibia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPO Box 22970<br \/>\nWindhoek<br \/>\nNamibia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sra. Marie Th\u00e9r\u00e8se Av\u00e9meka, Embajadora<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+264) (61) 240 796<br \/>\n<strong>Fax:<\/strong> (+264) (61) 240 796<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes a jueves: 08.30 a 13.00 y 14.00 a 16.00<br \/>\nviernes: 08.30 a 13.00<\/p>\n<div id=\"trave-330271613\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada congole\u00f1a en Windhoek, Namibia Direcci\u00f3n: PO Box 22970 Windhoek Namibia Embajador: Sra. Marie Th\u00e9r\u00e8se Av\u00e9meka, Embajadora Tel\u00e9fono: (+264) (61) 240 796 Fax: (+264) (61) 240 796 Email: Sitio web: Horas de oficina: Lunes a jueves: 08.30 a 13.00 y 14.00 a 16.00 viernes: 08.30 a 13.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13363,14727,6076,13362],"tags":[12975],"class_list":["post-124883","post","type-post","status-publish","format-standard","hentry","category-embajadas-congolenas-republica-del-congo-de","category-embajadas-en-namibia","category-namibia","category-republica-del-congo-de","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124883"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=124883"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124883\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=124883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=124883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=124883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}