{"id":124765,"date":"2019-09-01T08:15:14","date_gmt":"2019-09-01T08:15:14","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-serbia-en-maputo-mozambique\/"},"modified":"2019-09-01T08:15:14","modified_gmt":"2019-09-01T08:15:14","slug":"consulado-de-serbia-en-maputo-mozambique","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-serbia-en-maputo-mozambique\/","title":{"rendered":"Consulado de Serbia en Maputo, Mozambique"},"content":{"rendered":"<div id=\"trave-2771167846\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado serbio en Maputo, Mozambique<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMaputo<br \/>\nMozambique<br \/>\n<strong><br \/>\nEmbajador:<\/strong> John William Kachamila, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3813817396\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado serbio en Maputo, Mozambique Direcci\u00f3n: Maputo Mozambique Embajador: John William Kachamila, C\u00f3nsul Honorario Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14720,13606,6056,6450],"tags":[12978],"class_list":["post-124765","post","type-post","status-publish","format-standard","hentry","category-consulados-en-mozambique","category-consulados-serbios","category-mozambique","category-serbia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124765"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=124765"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124765\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=124765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=124765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=124765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}