{"id":124625,"date":"2019-09-01T08:13:52","date_gmt":"2019-09-01T08:13:52","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-bielorrusia-en-casablanca-marruecos\/"},"modified":"2019-09-01T08:13:52","modified_gmt":"2019-09-01T08:13:52","slug":"consulado-de-bielorrusia-en-casablanca-marruecos","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-bielorrusia-en-casablanca-marruecos\/","title":{"rendered":"Consulado de Bielorrusia en Casablanca, Marruecos"},"content":{"rendered":"<div id=\"trave-2670110446\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado Bielorruso en Casablanca, Marruecos<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCasablanca<br \/>\nMarruecos<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Salaheddine Aboulghali, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+212) 661 354 756<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> salaheddine.aboulghali@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-744354812\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado Bielorruso en Casablanca, Marruecos Direcci\u00f3n: Casablanca Marruecos Embajador: Salaheddine Aboulghali, C\u00f3nsul Honorario Tel\u00e9fono: (+212) 661 354 756 Fax: Email: salaheddine.aboulghali@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13554,13609,14712,13292],"tags":[12978],"class_list":["post-124625","post","type-post","status-publish","format-standard","hentry","category-bielorrusia","category-consulados-de-bielorrusia","category-consulados-en-marruecos","category-marruecos","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124625"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=124625"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124625\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=124625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=124625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=124625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}