{"id":124354,"date":"2019-09-01T08:10:39","date_gmt":"2019-09-01T08:10:39","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-sri-lanka-en-monaco-monaco\/"},"modified":"2019-09-01T08:10:39","modified_gmt":"2019-09-01T08:10:39","slug":"consulado-de-sri-lanka-en-monaco-monaco","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-sri-lanka-en-monaco-monaco\/","title":{"rendered":"Consulado de Sri Lanka en M\u00f3naco, M\u00f3naco"},"content":{"rendered":"<div id=\"trave-1180835453\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Sri Lanka en M\u00f3naco, M\u00f3naco<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nLes orchid\u00e9es<br \/>\n16, rue RP Louis Frolla<br \/>\n98 000 M\u00f3naco<br \/>\nM\u00f3naco<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Antoine William Piccione, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+377) 6 78 63 57 14<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> consulatsrilanka@monaco.mc<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-629615592\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Sri Lanka en M\u00f3naco, M\u00f3naco Direcci\u00f3n: Les orchid\u00e9es 16, rue RP Louis Frolla 98 000 M\u00f3naco M\u00f3naco Embajador: Mr Antoine William Piccione, C\u00f3nsul Honorario Tel\u00e9fono: (+377) 6 78 63 57 14 Fax: Email: consulatsrilanka@monaco.mc Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13249,14700,6017,6578],"tags":[12978],"class_list":["post-124354","post","type-post","status-publish","format-standard","hentry","category-consulados-de-sri-lanka","category-consulados-en-monaco","category-monaco","category-sri-lanka","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124354"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=124354"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124354\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=124354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=124354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=124354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}