{"id":124337,"date":"2019-09-01T08:10:30","date_gmt":"2019-09-01T08:10:30","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-madagascar-en-monaco-monaco\/"},"modified":"2019-09-01T08:10:30","modified_gmt":"2019-09-01T08:10:30","slug":"consulado-general-de-madagascar-en-monaco-monaco","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-madagascar-en-monaco-monaco\/","title":{"rendered":"Consulado General de Madagascar en M\u00f3naco, M\u00f3naco"},"content":{"rendered":"<div id=\"trave-3338357008\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Madagascar en M\u00f3naco, M\u00f3naco<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nLe Patio Palace<br \/>\n41,<br \/>\nMonacoAvenue Hector Otto98000<br \/>\nMonaco<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Jacques Ferreyrolles, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+377) 93.25.19.19<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2729585935\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Madagascar en M\u00f3naco, M\u00f3naco Direcci\u00f3n: Le Patio Palace 41, MonacoAvenue Hector Otto98000 Monaco Embajador: Jacques Ferreyrolles, C\u00f3nsul General Honorario Tel\u00e9fono: (+377) 93.25.19.19 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13748,14699,5901,6017],"tags":[12988],"class_list":["post-124337","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-madagascar","category-consulado-general-en-monaco","category-madagascar","category-monaco","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124337"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=124337"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124337\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=124337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=124337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=124337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}