{"id":124164,"date":"2019-09-01T08:08:41","date_gmt":"2019-09-01T08:08:41","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-espana-en-oaxaca-mexico\/"},"modified":"2019-09-01T08:08:41","modified_gmt":"2019-09-01T08:08:41","slug":"consulado-de-espana-en-oaxaca-mexico","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-espana-en-oaxaca-mexico\/","title":{"rendered":"Consulado de Espa\u00f1a en Oaxaca, M\u00e9xico"},"content":{"rendered":"<div id=\"trave-2831228910\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado espa\u00f1ol en Oaxaca, M\u00e9xico<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCol.Reforma de<br \/>\nOaxaca, Oaxaca<br \/>\nM\u00e9xico<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+52) (951) 518-0031<br \/>\n<strong>Fax:<\/strong> (+52) (951) 518-0100<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.00-14.00<\/p>\n<div id=\"trave-3696757724\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado espa\u00f1ol en Oaxaca, M\u00e9xico Direcci\u00f3n: Col.Reforma de Oaxaca, Oaxaca M\u00e9xico Embajador: Tel\u00e9fono: (+52) (951) 518-0031 Fax: (+52) (951) 518-0100 Email: Sitio web: Horas de oficina: 08.00-14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14680,13537,13134,5988],"tags":[12978],"class_list":["post-124164","post","type-post","status-publish","format-standard","hentry","category-consulados-en-mexico","category-consulados-espanoles","category-espana","category-mexico","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124164"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=124164"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/124164\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=124164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=124164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=124164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}