{"id":123903,"date":"2019-09-01T08:05:47","date_gmt":"2019-09-01T08:05:47","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-monaco-en-ciudad-de-mexico-mexico\/"},"modified":"2019-09-01T08:05:47","modified_gmt":"2019-09-01T08:05:47","slug":"consulado-de-monaco-en-ciudad-de-mexico-mexico","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-monaco-en-ciudad-de-mexico-mexico\/","title":{"rendered":"Consulado de M\u00f3naco en Ciudad de M\u00e9xico, M\u00e9xico"},"content":{"rendered":"<div id=\"trave-3939058769\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado Monegasco en Ciudad de M\u00e9xico, M\u00e9xico<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMonte Blanco 605<br \/>\nLomas de Chapultepec<br \/>\n11000 Ciudad de M\u00e9xico, DF<br \/>\nM\u00e9xico<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Adolfo I. Autrey Maza, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+52) 55 5520 0227<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> aautrey@superlog.com.mx<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2484597444\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado Monegasco en Ciudad de M\u00e9xico, M\u00e9xico Direcci\u00f3n: Monte Blanco 605 Lomas de Chapultepec 11000 Ciudad de M\u00e9xico, DF M\u00e9xico Embajador: Adolfo I. Autrey Maza, C\u00f3nsul Honorario Tel\u00e9fono: (+52) 55 5520 0227 Fax: Email: aautrey@superlog.com.mx Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14680,13541,5988,6017],"tags":[12978],"class_list":["post-123903","post","type-post","status-publish","format-standard","hentry","category-consulados-en-mexico","category-consulados-monegascos","category-mexico","category-monaco","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123903"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=123903"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123903\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=123903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=123903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=123903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}