{"id":123769,"date":"2019-09-01T08:04:21","date_gmt":"2019-09-01T08:04:21","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-dinamarca-en-fort-de-france-martinica\/"},"modified":"2019-09-01T08:04:21","modified_gmt":"2019-09-01T08:04:21","slug":"consulado-de-dinamarca-en-fort-de-france-martinica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-dinamarca-en-fort-de-france-martinica\/","title":{"rendered":"Consulado de Dinamarca en Fort-de-France, Martinica"},"content":{"rendered":"<div id=\"trave-2381909810\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado dan\u00e9s en Fort-de-France, Martinica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n97232 Le Francois<br \/>\nMartinique<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Yves Assier de Pompignan, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+596) 596 50 58 67<br \/>\n<strong>Fax:<\/strong> (+596) 596 50 58 67<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2626313666\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado dan\u00e9s en Fort-de-France, Martinica Direcci\u00f3n: 97232 Le Francois Martinique Embajador: Yves Assier de Pompignan, C\u00f3nsul Honorario Tel\u00e9fono: (+596) 596 50 58 67 Fax: (+596) 596 50 58 67 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13177,14670,13136,14669],"tags":[12978],"class_list":["post-123769","post","type-post","status-publish","format-standard","hentry","category-consulados-daneses","category-consulados-en-martinica","category-dinamarca","category-martinica","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123769"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=123769"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123769\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=123769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=123769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=123769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}